{"id":8934,"date":"2022-10-10T23:44:08","date_gmt":"2022-10-10T23:44:08","guid":{"rendered":"https:\/\/eduprofil.com\/company\/pinnacle-little-academy\/"},"modified":"2022-10-10T23:44:08","modified_gmt":"2022-10-10T23:44:08","slug":"pinnacle-little-academy","status":"publish","type":"company","link":"https:\/\/eduprofil.com\/fr\/company\/pinnacle-little-academy\/","title":{"rendered":"Pinnacle Little Academy"},"content":{"rendered":"<p>Pinnacle Little Academy est une cr&egrave;che-jardin d&rsquo;enfants con&ccedil;ue et am&eacute;nag&eacute;e pour favoriser l&rsquo;&eacute;veil et le d&eacute;veloppement personnel de l&rsquo;enfant dans un espace chaleureux qui accueille les enfants &acirc;g&eacute;s de 3 mois &agrave; 5 ans. Nous accompagnons les enfants dans le respect de leur personne et de leur rythme de d&eacute;veloppement.<\/p>\n<p>Chez Pinnacle Little Academy nous prenons en compte toutes les dimensions de l&rsquo;enfant : corporelle, &eacute;motionnelle, relationnelle, intellectuelle, et cr&eacute;ative. Nous privil&eacute;gions un suivi personnalis&eacute; et bienveillant en collaboration avec les familles afin d&rsquo;accompagner les enfants vers leur autonomie, leur socialisation et favoriser leur bien-&ecirc;tre.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pinnacle Little Academy est une cr&egrave;che-jardin d&rsquo;enfants con&ccedil;ue et am&eacute;nag&eacute;e pour favoriser l&rsquo;&eacute;veil et le d&eacute;veloppement personnel de l&rsquo;enfant dans un espace chaleureux qui accueille les enfants &acirc;g&eacute;s de 3&#8230;<\/p>","protected":false},"author":40,"featured_media":0,"template":"","meta":{"content-type":"","_themeisle_gutenberg_block_has_review":false},"company_category":[],"company_strength":[],"company_average_salary":[],"company_revenue":[],"class_list":["post-8934","company","type-company","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company\/8934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company"}],"about":[{"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/types\/company"}],"author":[{"embeddable":true,"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/users\/40"}],"wp:attachment":[{"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/media?parent=8934"}],"wp:term":[{"taxonomy":"company_category","embeddable":true,"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company_category?post=8934"},{"taxonomy":"company_strength","embeddable":true,"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company_strength?post=8934"},{"taxonomy":"company_average_salary","embeddable":true,"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company_average_salary?post=8934"},{"taxonomy":"company_revenue","embeddable":true,"href":"https:\/\/eduprofil.com\/fr\/wp-json\/wp\/v2\/company_revenue?post=8934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}